{"id":4080,"date":"2024-01-04T21:33:28","date_gmt":"2024-01-04T21:33:28","guid":{"rendered":"https:\/\/spectrumphotogallery.org\/home\/?page_id=4080"},"modified":"2025-03-05T21:09:49","modified_gmt":"2025-03-05T21:09:49","slug":"satellite-exhibitions","status":"publish","type":"page","link":"https:\/\/spectrumphotogallery.org\/home\/satellite-exhibitions\/","title":{"rendered":"Satellite Exhibitions"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"4080\" class=\"elementor elementor-4080\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6fd5ac62 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6fd5ac62\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6251b83f\" data-id=\"6251b83f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f6daf0e elementor-widget elementor-widget-text-editor\" data-id=\"f6daf0e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-99de71e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"99de71e\" data-element_type=\"section\"><div class=\"elementor-container elementor-column-gap-default\"><div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-32709f9\" data-id=\"32709f9\" data-element_type=\"column\"><div class=\"elementor-widget-wrap elementor-element-populated\"><div class=\"elementor-element elementor-element-210321d elementor-widget elementor-widget-text-editor\" data-id=\"210321d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\"><div class=\"elementor-widget-container\"><p><span style=\"text-decoration: underline;\"><a href=\"https:\/\/spectrumphotogallery.org\/home\/2025\/03\/05\/fresno-yosemite-international-airport\/\">Fresno Yosemite International Airport<\/a><\/span><\/p><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"elementor-section elementor-top-section elementor-element elementor-element-96b0ea7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"96b0ea7\" data-element_type=\"section\"><div class=\"elementor-container elementor-column-gap-default\"><div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c26fd67\" data-id=\"c26fd67\" data-element_type=\"column\"><div class=\"elementor-widget-wrap elementor-element-populated\"><div class=\"elementor-element elementor-element-8de820b elementor-widget elementor-widget-text-editor\" data-id=\"8de820b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\"><div class=\"elementor-widget-container\"><p><span style=\"text-decoration: underline;\"><a href=\"https:\/\/spectrumphotogallery.org\/home\/2025\/03\/05\/san-joaquin-river-parkway-and-conservation-trust\/\">San Joaquin River Parkway and Conservation Trust<\/a><\/span><\/p><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"elementor-section elementor-top-section elementor-element elementor-element-b0da290 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b0da290\" data-element_type=\"section\"><div class=\"elementor-container elementor-column-gap-default\"><div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e76279d\" data-id=\"e76279d\" data-element_type=\"column\"><div class=\"elementor-widget-wrap elementor-element-populated\"><div class=\"elementor-element elementor-element-2f463af elementor-widget elementor-widget-text-editor\" data-id=\"2f463af\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\"><div class=\"elementor-widget-container\"><p>The Big Fresno Fair<\/p><\/div><\/div><\/div><\/div><\/div><\/section>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7d4c36d elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"7d4c36d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f3f7f0e elementor-widget elementor-widget-text-editor\" data-id=\"f3f7f0e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">Exhibiting in our Satellite Exhibitions is an exclusive opportunity for our members.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-89a6297 elementor-widget elementor-widget-text-editor\" data-id=\"89a6297\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4 class=\"has-text-align-left has-medium-font-size\" style=\"text-align: center;\"><strong>Become a Member Today!<\/strong><\/h4>\n<p class=\"has-text-align-left\" style=\"text-align: center;\"><a href=\"https:\/\/spectrumphotogallery.org\/home\/membership\/\"><span style=\"text-decoration: underline;\"> Click here<\/span><\/a> for information on becoming an active or supporting member.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Fresno Yosemite International Airport San Joaquin River Parkway and Conservation Trust The Big Fresno Fair Exhibiting in our Satellite Exhibitions is an exclusive opportunity for our members. Become a Member Today! Click here for information on becoming an active or supporting member.<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"nf_dc_page":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ngg_post_thumbnail":0,"footnotes":""},"class_list":["post-4080","page","type-page","status-publish","hentry"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/spectrumphotogallery.org\/home\/wp-json\/wp\/v2\/pages\/4080","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/spectrumphotogallery.org\/home\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/spectrumphotogallery.org\/home\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/spectrumphotogallery.org\/home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/spectrumphotogallery.org\/home\/wp-json\/wp\/v2\/comments?post=4080"}],"version-history":[{"count":5,"href":"https:\/\/spectrumphotogallery.org\/home\/wp-json\/wp\/v2\/pages\/4080\/revisions"}],"predecessor-version":[{"id":5105,"href":"https:\/\/spectrumphotogallery.org\/home\/wp-json\/wp\/v2\/pages\/4080\/revisions\/5105"}],"wp:attachment":[{"href":"https:\/\/spectrumphotogallery.org\/home\/wp-json\/wp\/v2\/media?parent=4080"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}